{"id":62711,"date":"2025-04-10T11:51:07","date_gmt":"2025-04-10T09:51:07","guid":{"rendered":"https:\/\/www.itap.it\/prodotto\/084lk\/"},"modified":"2026-06-09T08:10:50","modified_gmt":"2026-06-09T06:10:50","slug":"084lk","status":"publish","type":"products","link":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/","title":{"rendered":"084LK"},"featured_media":109623,"template":"","class_list":["post-62711","products","type-products","status-publish","has-post-thumbnail","hentry","prod_cat-kugelhaehne-und-absperrschieber","prod_cat-ventile","prod_cat-griffe-fuer-kugelhaehne","prod_fam-griffe-fuer-kugelhaehne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>084LK Verschlie\u00dfbare Verriegelung f\u00fcr flachen Hebelgriff - Itap<\/title>\n<meta name=\"description\" content=\"Die Verriegelung kann an den Kugelh\u00e4hne und an den Wasserh\u00e4hnen f\u00fcr Schl\u00e4uche mit flachem Hebelgriff angebracht werden. Griffgr\u00f6\u00dfe entsprechend der jeweiligen Armatur gem\u00e4\u00df Tabelle Art. 084, 084V, 084G und 089B mit grauem Hintergrund.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"084LK Verschlie\u00dfbare Verriegelung f\u00fcr flachen Hebelgriff - Itap\" \/>\n<meta property=\"og:description\" content=\"Die Verriegelung kann an den Kugelh\u00e4hne und an den Wasserh\u00e4hnen f\u00fcr Schl\u00e4uche mit flachem Hebelgriff angebracht werden. Griffgr\u00f6\u00dfe entsprechend der jeweiligen Armatur gem\u00e4\u00df Tabelle Art. 084, 084V, 084G und 089B mit grauem Hintergrund.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/\" \/>\n<meta property=\"og:site_name\" content=\"Itap\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITAPspa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T06:10:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg\" \/><meta property=\"og:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/\",\"url\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/\",\"name\":\"084LK Verschlie\u00dfbare Verriegelung f\u00fcr flachen Hebelgriff - Itap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAwODRMSy5qcGc\\\/e143cb1bc6d6\\\/084lk.webp?w=0&h=0&c=0&p=62711\",\"datePublished\":\"2025-04-10T09:51:07+00:00\",\"dateModified\":\"2026-06-09T06:10:50+00:00\",\"description\":\"Die Verriegelung kann an den Kugelh\u00e4hne und an den Wasserh\u00e4hnen f\u00fcr Schl\u00e4uche mit flachem Hebelgriff angebracht werden. Griffgr\u00f6\u00dfe entsprechend der jeweiligen Armatur gem\u00e4\u00df Tabelle Art. 084, 084V, 084G und 089B mit grauem Hintergrund.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAwODRMSy5qcGc\\\/e143cb1bc6d6\\\/084lk.webp?w=0&h=0&c=0&p=62711\",\"contentUrl\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAwODRMSy5qcGc\\\/e143cb1bc6d6\\\/084lk.webp?w=0&h=0&c=0&p=62711\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/084lk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itap.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VENTILE\",\"item\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KUGELH\u00c4HNE UND ABSPERRSCHIEBER\",\"item\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"GRIFFE F\u00dcR KUGELH\u00c4HNE\",\"item\":\"https:\\\/\\\/www.itap.it\\\/de\\\/products\\\/ventile\\\/kugelhaehne-und-absperrschieber\\\/griffe-fuer-kugelhaehne\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"084LK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.itap.it\\\/de\\\/\",\"name\":\"Itap\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itap.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/#organization\",\"name\":\"ITAP S.p.A\",\"url\":\"https:\\\/\\\/www.itap.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itap.it\\\/wp-content\\\/uploads\\\/itap-logo-red.png\",\"contentUrl\":\"https:\\\/\\\/www.itap.it\\\/wp-content\\\/uploads\\\/itap-logo-red.png\",\"width\":3840,\"height\":1351,\"caption\":\"ITAP S.p.A\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ITAPspa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/itapspa\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itapspa-valves-heating-fittings\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"084LK Verschlie\u00dfbare Verriegelung f\u00fcr flachen Hebelgriff - Itap","description":"Die Verriegelung kann an den Kugelh\u00e4hne und an den Wasserh\u00e4hnen f\u00fcr Schl\u00e4uche mit flachem Hebelgriff angebracht werden. Griffgr\u00f6\u00dfe entsprechend der jeweiligen Armatur gem\u00e4\u00df Tabelle Art. 084, 084V, 084G und 089B mit grauem Hintergrund.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/","og_locale":"de_DE","og_type":"article","og_title":"084LK Verschlie\u00dfbare Verriegelung f\u00fcr flachen Hebelgriff - Itap","og_description":"Die Verriegelung kann an den Kugelh\u00e4hne und an den Wasserh\u00e4hnen f\u00fcr Schl\u00e4uche mit flachem Hebelgriff angebracht werden. Griffgr\u00f6\u00dfe entsprechend der jeweiligen Armatur gem\u00e4\u00df Tabelle Art. 084, 084V, 084G und 089B mit grauem Hintergrund.","og_url":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/","og_site_name":"Itap","article_publisher":"https:\/\/www.facebook.com\/ITAPspa\/","article_modified_time":"2026-06-09T06:10:50+00:00","og_image":[{"url":"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg","type":"","width":"","height":""},{"url":"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/","url":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/","name":"084LK Verschlie\u00dfbare Verriegelung f\u00fcr flachen Hebelgriff - Itap","isPartOf":{"@id":"https:\/\/www.itap.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/#primaryimage"},"image":{"@id":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/#primaryimage"},"thumbnailUrl":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAwODRMSy5qcGc\/e143cb1bc6d6\/084lk.webp?w=0&h=0&c=0&p=62711","datePublished":"2025-04-10T09:51:07+00:00","dateModified":"2026-06-09T06:10:50+00:00","description":"Die Verriegelung kann an den Kugelh\u00e4hne und an den Wasserh\u00e4hnen f\u00fcr Schl\u00e4uche mit flachem Hebelgriff angebracht werden. Griffgr\u00f6\u00dfe entsprechend der jeweiligen Armatur gem\u00e4\u00df Tabelle Art. 084, 084V, 084G und 089B mit grauem Hintergrund.","breadcrumb":{"@id":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/#primaryimage","url":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAwODRMSy5qcGc\/e143cb1bc6d6\/084lk.webp?w=0&h=0&c=0&p=62711","contentUrl":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAwODRMSy5qcGc\/e143cb1bc6d6\/084lk.webp?w=0&h=0&c=0&p=62711"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/084lk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itap.it\/de\/"},{"@type":"ListItem","position":2,"name":"VENTILE","item":"https:\/\/www.itap.it\/de\/products\/ventile\/"},{"@type":"ListItem","position":3,"name":"KUGELH\u00c4HNE UND ABSPERRSCHIEBER","item":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/"},{"@type":"ListItem","position":4,"name":"GRIFFE F\u00dcR KUGELH\u00c4HNE","item":"https:\/\/www.itap.it\/de\/products\/ventile\/kugelhaehne-und-absperrschieber\/griffe-fuer-kugelhaehne\/"},{"@type":"ListItem","position":5,"name":"084LK"}]},{"@type":"WebSite","@id":"https:\/\/www.itap.it\/de\/#website","url":"https:\/\/www.itap.it\/de\/","name":"Itap","description":"","publisher":{"@id":"https:\/\/www.itap.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itap.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.itap.it\/de\/#organization","name":"ITAP S.p.A","url":"https:\/\/www.itap.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.itap.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.itap.it\/wp-content\/uploads\/itap-logo-red.png","contentUrl":"https:\/\/www.itap.it\/wp-content\/uploads\/itap-logo-red.png","width":3840,"height":1351,"caption":"ITAP S.p.A"},"image":{"@id":"https:\/\/www.itap.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITAPspa\/","https:\/\/www.instagram.com\/itapspa","https:\/\/www.linkedin.com\/company\/itapspa-valves-heating-fittings\/"]}]}},"permalink_manager":null,"fifu_image_url":"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg","fifu_slider_image_url_0":"https:\/\/www.itap.it\/cat_files\/images\/itap084LK.jpg","_links":{"self":[{"href":"https:\/\/www.itap.it\/de\/wp-json\/wp\/v2\/products\/62711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itap.it\/de\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.itap.it\/de\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itap.it\/de\/wp-json\/wp\/v2\/media\/109623"}],"wp:attachment":[{"href":"https:\/\/www.itap.it\/de\/wp-json\/wp\/v2\/media?parent=62711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}