{"id":63084,"date":"2025-04-10T12:22:08","date_gmt":"2025-04-10T10:22:08","guid":{"rendered":"https:\/\/www.itap.it\/prodotto\/276xb\/"},"modified":"2026-06-09T08:44:31","modified_gmt":"2026-06-09T06:44:31","slug":"276xb","status":"publish","type":"products","link":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/","title":{"rendered":"276XB"},"featured_media":110479,"template":"","class_list":["post-63084","products","type-products","status-publish","has-post-thumbnail","hentry","prod_cat-valvulas-de-esfera-y-valvulas-de-compuerta","prod_cat-valvulas","prod_cat-valvulas-de-esfera-paso-total-madrid","prod_fam-valvulas-de-esfera-paso-total-madrid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>276XB V\u00e1lvula de esfera Madrid, paso total, con palanca plana de acero inoxidable - Itap<\/title>\n<meta name=\"description\" content=\"Indicadas para el uso en instalaciones hidr\u00e1ulicas, de calefacci\u00f3n, de acondicionamiento y neum\u00e1ticas.MADRID\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"276XB V\u00e1lvula de esfera Madrid, paso total, con palanca plana de acero inoxidable - Itap\" \/>\n<meta property=\"og:description\" content=\"Indicadas para el uso en instalaciones hidr\u00e1ulicas, de calefacci\u00f3n, de acondicionamiento y neum\u00e1ticas.MADRID\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/\" \/>\n<meta property=\"og:site_name\" content=\"Itap\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITAPspa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T06:44:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg\" \/><meta property=\"og:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/\",\"url\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/\",\"name\":\"276XB V\u00e1lvula de esfera Madrid, paso total, con palanca plana de acero inoxidable - Itap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAyNzZYQi5qcGc\\\/86cb464830da\\\/276xb.webp?w=0&h=0&c=0&p=63084\",\"datePublished\":\"2025-04-10T10:22:08+00:00\",\"dateModified\":\"2026-06-09T06:44:31+00:00\",\"description\":\"Indicadas para el uso en instalaciones hidr\u00e1ulicas, de calefacci\u00f3n, de acondicionamiento y neum\u00e1ticas.MADRID\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAyNzZYQi5qcGc\\\/86cb464830da\\\/276xb.webp?w=0&h=0&c=0&p=63084\",\"contentUrl\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAyNzZYQi5qcGc\\\/86cb464830da\\\/276xb.webp?w=0&h=0&c=0&p=63084\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/276xb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itap.it\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00c1LVULAS\",\"item\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"V\u00c1LVULAS DE ESFERA Y V\u00c1LVULAS DE COMPUERTA\",\"item\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"V\u00c1LVULAS DE ESFERA PASO TOTAL MADRID\",\"item\":\"https:\\\/\\\/www.itap.it\\\/es\\\/products\\\/valvulas\\\/valvulas-de-esfera-y-valvulas-de-compuerta\\\/valvulas-de-esfera-paso-total-madrid\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"276XB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itap.it\\\/es\\\/\",\"name\":\"Itap\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itap.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/#organization\",\"name\":\"ITAP S.p.A\",\"url\":\"https:\\\/\\\/www.itap.it\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itap.it\\\/wp-content\\\/uploads\\\/itap-logo-red.png\",\"contentUrl\":\"https:\\\/\\\/www.itap.it\\\/wp-content\\\/uploads\\\/itap-logo-red.png\",\"width\":3840,\"height\":1351,\"caption\":\"ITAP S.p.A\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ITAPspa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/itapspa\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itapspa-valves-heating-fittings\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"276XB V\u00e1lvula de esfera Madrid, paso total, con palanca plana de acero inoxidable - Itap","description":"Indicadas para el uso en instalaciones hidr\u00e1ulicas, de calefacci\u00f3n, de acondicionamiento y neum\u00e1ticas.MADRID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/","og_locale":"es_ES","og_type":"article","og_title":"276XB V\u00e1lvula de esfera Madrid, paso total, con palanca plana de acero inoxidable - Itap","og_description":"Indicadas para el uso en instalaciones hidr\u00e1ulicas, de calefacci\u00f3n, de acondicionamiento y neum\u00e1ticas.MADRID","og_url":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/","og_site_name":"Itap","article_publisher":"https:\/\/www.facebook.com\/ITAPspa\/","article_modified_time":"2026-06-09T06:44:31+00:00","og_image":[{"url":"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg","type":"","width":"","height":""},{"url":"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/","url":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/","name":"276XB V\u00e1lvula de esfera Madrid, paso total, con palanca plana de acero inoxidable - Itap","isPartOf":{"@id":"https:\/\/www.itap.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/#primaryimage"},"image":{"@id":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/#primaryimage"},"thumbnailUrl":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAyNzZYQi5qcGc\/86cb464830da\/276xb.webp?w=0&h=0&c=0&p=63084","datePublished":"2025-04-10T10:22:08+00:00","dateModified":"2026-06-09T06:44:31+00:00","description":"Indicadas para el uso en instalaciones hidr\u00e1ulicas, de calefacci\u00f3n, de acondicionamiento y neum\u00e1ticas.MADRID","breadcrumb":{"@id":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/#primaryimage","url":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAyNzZYQi5qcGc\/86cb464830da\/276xb.webp?w=0&h=0&c=0&p=63084","contentUrl":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAyNzZYQi5qcGc\/86cb464830da\/276xb.webp?w=0&h=0&c=0&p=63084"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/276xb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itap.it\/es\/"},{"@type":"ListItem","position":2,"name":"V\u00c1LVULAS","item":"https:\/\/www.itap.it\/es\/products\/valvulas\/"},{"@type":"ListItem","position":3,"name":"V\u00c1LVULAS DE ESFERA Y V\u00c1LVULAS DE COMPUERTA","item":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/"},{"@type":"ListItem","position":4,"name":"V\u00c1LVULAS DE ESFERA PASO TOTAL MADRID","item":"https:\/\/www.itap.it\/es\/products\/valvulas\/valvulas-de-esfera-y-valvulas-de-compuerta\/valvulas-de-esfera-paso-total-madrid\/"},{"@type":"ListItem","position":5,"name":"276XB"}]},{"@type":"WebSite","@id":"https:\/\/www.itap.it\/es\/#website","url":"https:\/\/www.itap.it\/es\/","name":"Itap","description":"","publisher":{"@id":"https:\/\/www.itap.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itap.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.itap.it\/es\/#organization","name":"ITAP S.p.A","url":"https:\/\/www.itap.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.itap.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itap.it\/wp-content\/uploads\/itap-logo-red.png","contentUrl":"https:\/\/www.itap.it\/wp-content\/uploads\/itap-logo-red.png","width":3840,"height":1351,"caption":"ITAP S.p.A"},"image":{"@id":"https:\/\/www.itap.it\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITAPspa\/","https:\/\/www.instagram.com\/itapspa","https:\/\/www.linkedin.com\/company\/itapspa-valves-heating-fittings\/"]}]}},"permalink_manager":null,"fifu_image_url":"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg","fifu_slider_image_url_0":"https:\/\/www.itap.it\/cat_files\/images\/itap276XB.jpg","_links":{"self":[{"href":"https:\/\/www.itap.it\/es\/wp-json\/wp\/v2\/products\/63084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itap.it\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.itap.it\/es\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itap.it\/es\/wp-json\/wp\/v2\/media\/110479"}],"wp:attachment":[{"href":"https:\/\/www.itap.it\/es\/wp-json\/wp\/v2\/media?parent=63084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}