{"id":62359,"date":"2025-04-10T11:35:37","date_gmt":"2025-04-10T09:35:37","guid":{"rendered":"https:\/\/www.itap.it\/prodotto\/187ca\/"},"modified":"2026-06-09T07:57:01","modified_gmt":"2026-06-09T05:57:01","slug":"187ca","status":"publish","type":"products","link":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/","title":{"rendered":"187CA"},"featured_media":109719,"template":"","class_list":["post-62359","products","type-products","status-publish","has-post-thumbnail","hentry","prod_cat-doseur-proportionnel-polyphosphate","prod_cat-reducteurs-de-pression-et-accessoires-pour-chaufferie","prod_fam-doseur-proportionnel-polyphosphate"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>187CA Recharge de polyphosphate solide pour I-Doser - Itap<\/title>\n<meta name=\"description\" content=\"DOSEUR PROPORTIONNEL POLYPHOSPHATE Le doseur proportionnel polyphosphate, produit par ITAP, est con\u00e7u pour le traitement anticalcaire et anticorrosion dans les installations de production d\u2019eau chaude sanitaire. Le doseur doit \u00eatre install\u00e9 dans la conduite d\u2019eau froide \u00e0 l\u2019entr\u00e9e de la chaudi\u00e8re et, en g\u00e9n\u00e9ral, sur les g\u00e9n\u00e9rateurs de chaleur (ballons d\u2019eau chaude et chauffe-eau). Il peut \u00eatre install\u00e9 m\u00eame \u00e0 l\u2019entr\u00e9e des machines \u00e0 laver et lave-vaisselle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"187CA Recharge de polyphosphate solide pour I-Doser - Itap\" \/>\n<meta property=\"og:description\" content=\"DOSEUR PROPORTIONNEL POLYPHOSPHATE Le doseur proportionnel polyphosphate, produit par ITAP, est con\u00e7u pour le traitement anticalcaire et anticorrosion dans les installations de production d\u2019eau chaude sanitaire. Le doseur doit \u00eatre install\u00e9 dans la conduite d\u2019eau froide \u00e0 l\u2019entr\u00e9e de la chaudi\u00e8re et, en g\u00e9n\u00e9ral, sur les g\u00e9n\u00e9rateurs de chaleur (ballons d\u2019eau chaude et chauffe-eau). Il peut \u00eatre install\u00e9 m\u00eame \u00e0 l\u2019entr\u00e9e des machines \u00e0 laver et lave-vaisselle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/\" \/>\n<meta property=\"og:site_name\" content=\"Itap\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ITAPspa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T05:57:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg\" \/><meta property=\"og:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/\",\"url\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/\",\"name\":\"187CA Recharge de polyphosphate solide pour I-Doser - Itap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAxODdDQS5qcGc\\\/b4e8d6e1b454\\\/187ca.webp?w=0&h=0&c=0&p=62359\",\"datePublished\":\"2025-04-10T09:35:37+00:00\",\"dateModified\":\"2026-06-09T05:57:01+00:00\",\"description\":\"DOSEUR PROPORTIONNEL POLYPHOSPHATE Le doseur proportionnel polyphosphate, produit par ITAP, est con\u00e7u pour le traitement anticalcaire et anticorrosion dans les installations de production d\u2019eau chaude sanitaire. Le doseur doit \u00eatre install\u00e9 dans la conduite d\u2019eau froide \u00e0 l\u2019entr\u00e9e de la chaudi\u00e8re et, en g\u00e9n\u00e9ral, sur les g\u00e9n\u00e9rateurs de chaleur (ballons d\u2019eau chaude et chauffe-eau). Il peut \u00eatre install\u00e9 m\u00eame \u00e0 l\u2019entr\u00e9e des machines \u00e0 laver et lave-vaisselle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAxODdDQS5qcGc\\\/b4e8d6e1b454\\\/187ca.webp?w=0&h=0&c=0&p=62359\",\"contentUrl\":\"https:\\\/\\\/wp.fifu.app\\\/itap.it\\\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAxODdDQS5qcGc\\\/b4e8d6e1b454\\\/187ca.webp?w=0&h=0&c=0&p=62359\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/187ca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00c9DUCTEURS DE PRESSION ET ACCESSOIRES POUR CHAUFFERIE\",\"item\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DOSEUR PROPORTIONNEL POLYPHOSPHATE\",\"item\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/products\\\/reducteurs-de-pression-et-accessoires-pour-chaufferie\\\/doseur-proportionnel-polyphosphate\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"187CA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/\",\"name\":\"Itap\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/#organization\",\"name\":\"ITAP S.p.A\",\"url\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itap.it\\\/wp-content\\\/uploads\\\/itap-logo-red.png\",\"contentUrl\":\"https:\\\/\\\/www.itap.it\\\/wp-content\\\/uploads\\\/itap-logo-red.png\",\"width\":3840,\"height\":1351,\"caption\":\"ITAP S.p.A\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itap.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ITAPspa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/itapspa\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itapspa-valves-heating-fittings\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"187CA Recharge de polyphosphate solide pour I-Doser - Itap","description":"DOSEUR PROPORTIONNEL POLYPHOSPHATE Le doseur proportionnel polyphosphate, produit par ITAP, est con\u00e7u pour le traitement anticalcaire et anticorrosion dans les installations de production d\u2019eau chaude sanitaire. Le doseur doit \u00eatre install\u00e9 dans la conduite d\u2019eau froide \u00e0 l\u2019entr\u00e9e de la chaudi\u00e8re et, en g\u00e9n\u00e9ral, sur les g\u00e9n\u00e9rateurs de chaleur (ballons d\u2019eau chaude et chauffe-eau). Il peut \u00eatre install\u00e9 m\u00eame \u00e0 l\u2019entr\u00e9e des machines \u00e0 laver et lave-vaisselle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/","og_locale":"fr_FR","og_type":"article","og_title":"187CA Recharge de polyphosphate solide pour I-Doser - Itap","og_description":"DOSEUR PROPORTIONNEL POLYPHOSPHATE Le doseur proportionnel polyphosphate, produit par ITAP, est con\u00e7u pour le traitement anticalcaire et anticorrosion dans les installations de production d\u2019eau chaude sanitaire. Le doseur doit \u00eatre install\u00e9 dans la conduite d\u2019eau froide \u00e0 l\u2019entr\u00e9e de la chaudi\u00e8re et, en g\u00e9n\u00e9ral, sur les g\u00e9n\u00e9rateurs de chaleur (ballons d\u2019eau chaude et chauffe-eau). Il peut \u00eatre install\u00e9 m\u00eame \u00e0 l\u2019entr\u00e9e des machines \u00e0 laver et lave-vaisselle.","og_url":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/","og_site_name":"Itap","article_publisher":"https:\/\/www.facebook.com\/ITAPspa\/","article_modified_time":"2026-06-09T05:57:01+00:00","og_image":[{"url":"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg","type":"","width":"","height":""},{"url":"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/","url":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/","name":"187CA Recharge de polyphosphate solide pour I-Doser - Itap","isPartOf":{"@id":"https:\/\/www.itap.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/#primaryimage"},"image":{"@id":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/#primaryimage"},"thumbnailUrl":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAxODdDQS5qcGc\/b4e8d6e1b454\/187ca.webp?w=0&h=0&c=0&p=62359","datePublished":"2025-04-10T09:35:37+00:00","dateModified":"2026-06-09T05:57:01+00:00","description":"DOSEUR PROPORTIONNEL POLYPHOSPHATE Le doseur proportionnel polyphosphate, produit par ITAP, est con\u00e7u pour le traitement anticalcaire et anticorrosion dans les installations de production d\u2019eau chaude sanitaire. Le doseur doit \u00eatre install\u00e9 dans la conduite d\u2019eau froide \u00e0 l\u2019entr\u00e9e de la chaudi\u00e8re et, en g\u00e9n\u00e9ral, sur les g\u00e9n\u00e9rateurs de chaleur (ballons d\u2019eau chaude et chauffe-eau). Il peut \u00eatre install\u00e9 m\u00eame \u00e0 l\u2019entr\u00e9e des machines \u00e0 laver et lave-vaisselle.","breadcrumb":{"@id":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/#primaryimage","url":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAxODdDQS5qcGc\/b4e8d6e1b454\/187ca.webp?w=0&h=0&c=0&p=62359","contentUrl":"https:\/\/wp.fifu.app\/itap.it\/aHR0cHM6Ly93d3cuaXRhcC5pdC9jYXRfZmlsZXMvaW1hZ2VzL2l0YXAxODdDQS5qcGc\/b4e8d6e1b454\/187ca.webp?w=0&h=0&c=0&p=62359"},{"@type":"BreadcrumbList","@id":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/187ca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itap.it\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00c9DUCTEURS DE PRESSION ET ACCESSOIRES POUR CHAUFFERIE","item":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/"},{"@type":"ListItem","position":3,"name":"DOSEUR PROPORTIONNEL POLYPHOSPHATE","item":"https:\/\/www.itap.it\/fr\/products\/reducteurs-de-pression-et-accessoires-pour-chaufferie\/doseur-proportionnel-polyphosphate\/"},{"@type":"ListItem","position":4,"name":"187CA"}]},{"@type":"WebSite","@id":"https:\/\/www.itap.it\/fr\/#website","url":"https:\/\/www.itap.it\/fr\/","name":"Itap","description":"","publisher":{"@id":"https:\/\/www.itap.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itap.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itap.it\/fr\/#organization","name":"ITAP S.p.A","url":"https:\/\/www.itap.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itap.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.itap.it\/wp-content\/uploads\/itap-logo-red.png","contentUrl":"https:\/\/www.itap.it\/wp-content\/uploads\/itap-logo-red.png","width":3840,"height":1351,"caption":"ITAP S.p.A"},"image":{"@id":"https:\/\/www.itap.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITAPspa\/","https:\/\/www.instagram.com\/itapspa","https:\/\/www.linkedin.com\/company\/itapspa-valves-heating-fittings\/"]}]}},"permalink_manager":null,"fifu_image_url":"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg","fifu_slider_image_url_0":"https:\/\/www.itap.it\/cat_files\/images\/itap187CA.jpg","_links":{"self":[{"href":"https:\/\/www.itap.it\/fr\/wp-json\/wp\/v2\/products\/62359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itap.it\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.itap.it\/fr\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itap.it\/fr\/wp-json\/wp\/v2\/media\/109719"}],"wp:attachment":[{"href":"https:\/\/www.itap.it\/fr\/wp-json\/wp\/v2\/media?parent=62359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}